{"id":378,"count":8,"description":"","link":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/","name":"Tumble dryers","slug":"tumble-dryers","taxonomy":"product_cat","parent":376,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tumble dryers Archives - Marketplace 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tumble dryers Archives - Marketplace 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketplace 2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/product-category\\\/appliances\\\/laundry\\\/tumble-dryers\\\/\",\"url\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/product-category\\\/appliances\\\/laundry\\\/tumble-dryers\\\/\",\"name\":\"Tumble dryers Archives - Marketplace 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/product-category\\\/appliances\\\/laundry\\\/tumble-dryers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/product-category\\\/appliances\\\/laundry\\\/tumble-dryers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appliances\",\"item\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/product-category\\\/appliances\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Laundry\",\"item\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/product-category\\\/appliances\\\/laundry\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tumble dryers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/#website\",\"url\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/\",\"name\":\"Marketplace 2\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/woodmart.xtemos.com\\\/marketplace2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tumble dryers Archives - Marketplace 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/","og_locale":"en_US","og_type":"article","og_title":"Tumble dryers Archives - Marketplace 2","og_url":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/","og_site_name":"Marketplace 2","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/","url":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/","name":"Tumble dryers Archives - Marketplace 2","isPartOf":{"@id":"https:\/\/woodmart.xtemos.com\/marketplace2\/#website"},"breadcrumb":{"@id":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/tumble-dryers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/woodmart.xtemos.com\/marketplace2\/"},{"@type":"ListItem","position":2,"name":"Appliances","item":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/"},{"@type":"ListItem","position":3,"name":"Laundry","item":"https:\/\/woodmart.xtemos.com\/marketplace2\/product-category\/appliances\/laundry\/"},{"@type":"ListItem","position":4,"name":"Tumble dryers"}]},{"@type":"WebSite","@id":"https:\/\/woodmart.xtemos.com\/marketplace2\/#website","url":"https:\/\/woodmart.xtemos.com\/marketplace2\/","name":"Marketplace 2","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woodmart.xtemos.com\/marketplace2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/woodmart.xtemos.com\/marketplace2\/wp-json\/wp\/v2\/product_cat\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woodmart.xtemos.com\/marketplace2\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/woodmart.xtemos.com\/marketplace2\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/woodmart.xtemos.com\/marketplace2\/wp-json\/wp\/v2\/product_cat\/376"}],"wp:post_type":[{"href":"https:\/\/woodmart.xtemos.com\/marketplace2\/wp-json\/wp\/v2\/product?product_cat=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}